{"id":6550,"date":"2023-06-05T14:08:18","date_gmt":"2023-06-05T14:08:18","guid":{"rendered":"http:\/\/sanignacioconcepcion.cl\/sitio\/?p=6550"},"modified":"2023-06-08T15:48:59","modified_gmt":"2023-06-08T15:48:59","slug":"semana-de-la-convivencia-escolar-uniendo-a-la-comunidad-en-el-dialogo-por-el-buen-trato","status":"publish","type":"post","link":"http:\/\/sanignacioconcepcion.cl\/sitio\/semana-de-la-convivencia-escolar-uniendo-a-la-comunidad-en-el-dialogo-por-el-buen-trato\/","title":{"rendered":"Semana de la Convivencia Escolar: Uniendo a la comunidad  en el di\u00e1logo por el buen trato"},"content":{"rendered":"<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">Nuestra comunidad educativa celebr\u00f3 con gran \u00e9xito la Semana de la Convivencia Escolar, celebraci\u00f3n dedicada a promover el di\u00e1logo, la reflexi\u00f3n y el buen trato entre todos\/as.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">Durante los d\u00edas 29, 30 y 31 de mayo, se llevaron a cabo diversas actividades que fomentaron un ambiente de respeto y colaboraci\u00f3n. Esta celebraci\u00f3n busc\u00f3 fortalecer los lazos entre los\/las estudiantes, educadores, as\u00ed como tambi\u00e9n generar espacios de reflexi\u00f3n sobre la importancia del buen trato en la formaci\u00f3n de los estudiantes.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">Las jornadas de reflexi\u00f3n fueron uno de los puntos destacados de la semana, instancias donde contamos con la colaboraci\u00f3n de apoderados quienes participaron directamente con sus cursos en temas relacionados con la convivencia, la comunicaci\u00f3n efectiva y el buen trato, finalizando el \u00faltimo d\u00edascon mensajes sobre las acciones y\/o actitudes que nunca m\u00e1s deber\u00edan pasar en \u00abel Colegio que sue\u00f1o\u00bb&#8230; un Colegio que sea un espacio de bienestar, de confianza y cuidado.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"WdYUQQ text-decoration-none text-strikethrough-none\">Por su parte, los y las educadoras tambi\u00e9n participaron de una tarde de di\u00e1logo en base a tres \u00e1mbitos (emociones, pensamientos y acciones) para un buen trato y sana convivencia.<\/span><\/p>\n<p>Estos espacios permitieron a ambas partes expresar sus inquietudes, compartir experiencias y proponer ideas para mejorar la convivencia en la comunidad educativa, compartiendo a trav\u00e9s de din\u00e1micas de confianza y actividades art\u00edsticas, que no s\u00f3lo promovieron el buen trato, sino tambi\u00e9n fortalecieron el trabajo en equipo y la creatividad.<\/p>\n<p>\u00abEstamos muy contentos con los resultados de esta Semana de la Convivencia. Fue un espacio enriquecedor donde las familias y los educadores pudieron compartir, reflexionar y fortalecer lazos. Creemos firmemente en la importancia del buen trato como base fundamental para una educaci\u00f3n integral y estamos comprometidos en seguir trabajando juntos en pro de una convivencia positiva\u00bb, expres\u00f3 el Encargado de Convivencia Escolar, Sr. Jos\u00e9 Mora.<\/p>\n<p>Esperamos que esta Semana de la Convivencia sea el punto de partida para seguir impulsando acciones y programas que promuevan el buen trato y la buena convivencia en todo \u00e1mbito. El compromiso de padres, educadores y estudiantes es fundamental para construir una sociedad m\u00e1s respetuosa, solidaria y equitativa. <a href=\"https:\/\/photos.app.goo.gl\/gMvTaYHfNxufh9tFA\">ver fotograf\u00edas<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra comunidad educativa celebr\u00f3 con gran \u00e9xito la Semana de la Convivencia Escolar, celebraci\u00f3n dedicada a promover el di\u00e1logo, la reflexi\u00f3n y el buen trato entre todos\/as. Durante los d\u00edas 29, 30 y 31 de mayo, se llevaron a cabo diversas actividades que fomentaron un ambiente de respeto y colaboraci\u00f3n. Esta celebraci\u00f3n busc\u00f3 fortalecer los&hellip;<\/p>\n","protected":false},"author":1,"featured_media":6551,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/posts\/6550"}],"collection":[{"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/comments?post=6550"}],"version-history":[{"count":1,"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/posts\/6550\/revisions"}],"predecessor-version":[{"id":6552,"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/posts\/6550\/revisions\/6552"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/media\/6551"}],"wp:attachment":[{"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/media?parent=6550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/categories?post=6550"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/tags?post=6550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}