{"id":6611,"date":"2023-06-23T11:52:55","date_gmt":"2023-06-23T11:52:55","guid":{"rendered":"http:\/\/sanignacioconcepcion.cl\/sitio\/?p=6611"},"modified":"2023-06-30T11:54:15","modified_gmt":"2023-06-30T11:54:15","slug":"jornada-de-directores-as-de-pastoral-y-formacion-rei","status":"publish","type":"post","link":"http:\/\/sanignacioconcepcion.cl\/sitio\/jornada-de-directores-as-de-pastoral-y-formacion-rei\/","title":{"rendered":"Jornada de Directores\/as de Pastoral y Formaci\u00f3n REI"},"content":{"rendered":"<p>El jueves 15 y el viernes 16 de junio, en la Casa de Retiros de Padre Hurtado, se llev\u00f3 a cabo la Jornada Anual de Directores\/as de Pastoral y Formaci\u00f3n de los colegios y escuelas de la Red Educacional Ignaciana (REI).<\/p>\n<p>La instancia tuvo como objetivo proyectar el trabajo del \u00c1rea desde la implementaci\u00f3n del modelo com\u00fan de Pastoral y Formaci\u00f3n (PyF) de la REI, as\u00ed como tambi\u00e9n generar un espacio de encuentro y trabajo presencial para que los participantes se reconocieran en una misi\u00f3n com\u00fan. En este contexto, los asistentes reflexionaron en torno a la importancia del desarrollo de la espiritualidad e identificaron \u00e1mbitos de la gesti\u00f3n del \u00e1rea para trabajarlos en sus propios equipos.<\/p>\n<p>Una parte importante de la jornada estuvo orientada a la revisi\u00f3n de los avances de las comisiones de renovaci\u00f3n de la Pastoral: Apostolado y Servicio; Afectividad y Sexualidad; Religiosidad post Primera Comuni\u00f3n, e Inducci\u00f3n a Familias Nuevas. Esto, en respuesta al env\u00edo 4 del Plan Estrat\u00e9gico del \u00c1rea de Educaci\u00f3n Escolar de la Compa\u00f1\u00eda de Jes\u00fas en Chile.<\/p>\n<p>Durante el segundo d\u00eda, los presentes participaron de un taller de Oraci\u00f3n Ignaciana que contempla un m\u00e9todo desarrollado por la Provincia de Argentina y Uruguay, que lleva al aula la experiencia de los Ejercicios Espirituales. Este taller fue guiado por Nathalie Raymond, laica francesa formada en la metodolog\u00eda, quien comenta que este m\u00e9todo \u201ces un tesoro, no solo para los colegios jesuitas, sino que para toda la iglesia y no solo para ni\u00f1os, sino que para adultos, porque hace entrar en la amistad con Cristo meditando el evangelio que es palabra de vida\u201d. En ese plano, agrega que junto a los Directores\/as hicieron la oraci\u00f3n de la misma manera en que se hace con los ni\u00f1os, siguiendo todos los pasos que se inician con la pregunta \u201ca d\u00f3nde voy y a qu\u00e9\u201d. \u201cEllos hacen la experiencia de Dios y cuando uno experimenta su presencia no se necesitan muchos discursos adicionales; es hacer la experiencia de un Dios que vive, nos ama y quiere lo mejor para nosotros\u201d, asevera Nathalie.<\/p>\n<p>Al finalizar la jornada, los participantes expusieron experiencias exitosas de los colegios y escuelas que apuntaran a un proyecto del \u00c1rea y a la Gesti\u00f3n Directiva.<\/p>\n<p><strong>La visi\u00f3n de los participantes <\/strong><\/p>\n<p>Andrea Fones, Directora de Pastoral y Formaci\u00f3n del Colegio Nuestra Se\u00f1ora del Camino, comenta que este fue un encuentro muy fecundo, dado que en todas las comunidades educativas de la REI se est\u00e1 instalando el modelo de PyF con grandes desaf\u00edos. \u201cMirar los ritmos de todos los colegios y las preguntas ha sido s\u00faper bonito. En t\u00e9rminos de la gesti\u00f3n del modelo, hemos visto los liderazgos y los \u00e1mbitos que tenemos que trabajar y abordar para que se pueda llevar a cabo. Se percibe el deseo de sistematizar e ir ahondando, pero con mucha esperanza de que este es el camino y eso ha sido una preciosa confirmaci\u00f3n\u201d, dice. Agrega que de la jornada se lleva, principalmente, poner en prioridad lo importante, porque lo emergente a veces distrae de la misi\u00f3n final y tambi\u00e9n muchos aspectos pr\u00e1cticos compartidos por sus pares estos d\u00edas.<\/p>\n<p>Por otro lado, destaca la riqueza de las comisiones de renovaci\u00f3n. \u201cSu trabajo nos ha hecho sentir en red al ver que hay otros que est\u00e1n aportando y que no somos los mismos; escucharlos empoderados, reuni\u00e9ndose sistem\u00e1ticamente y con reflexiones profundas ha sido muy enriquecedor\u201d, se\u00f1ala.<br \/>\nPor su parte, Cristian Rucal, Director de Pastoral y Formaci\u00f3n de la Escuela San Ignacio Calera de Tango, coincide con Andrea, puntualizando que este fue un espacio importante para compartir experiencias y sentirse parte de una red. \u201cMe llevo la participaci\u00f3n de la gesti\u00f3n, es decir, c\u00f3mo los hom\u00f3logos gestionan y c\u00f3mo se va instalando el modelo de PyF que estamos desarrollando. Eso es un gran aprendizaje y nos lleva a compartir ese trabajo (\u2026) En t\u00e9rminos pr\u00e1cticos, hemos vuelto a mirar las comunidades educativas y a revisar, cuestionar y problematizar la gesti\u00f3n de la Pastoral\u2026 no es f\u00e1cil gestionar un espacio de Pastoral porque eso nos lleva a que tenemos mirar nuestras propias competencias, perfiles y equipos para ir instalando el modelo con mucho di\u00e1logo dentro de cada comunidad\u201d asegura.<\/p>\n<p>Tambi\u00e9n resalta el trabajo de las comisiones de renovaci\u00f3n. \u201cEllos ya est\u00e1n elaborando un material y eso nos ayuda como insumo con la reflexi\u00f3n que estamos haciendo en los colegios dentro del modelo de PyF\u201d, concluye.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jueves 15 y el viernes 16 de junio, en la Casa de Retiros de Padre Hurtado, se llev\u00f3 a cabo la Jornada Anual de Directores\/as de Pastoral y Formaci\u00f3n de los colegios y escuelas de la Red Educacional Ignaciana (REI). La instancia tuvo como objetivo proyectar el trabajo del \u00c1rea desde la implementaci\u00f3n del&hellip;<\/p>\n","protected":false},"author":1,"featured_media":6612,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/posts\/6611"}],"collection":[{"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/comments?post=6611"}],"version-history":[{"count":1,"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/posts\/6611\/revisions"}],"predecessor-version":[{"id":6613,"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/posts\/6611\/revisions\/6613"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/media\/6612"}],"wp:attachment":[{"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/media?parent=6611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/categories?post=6611"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/tags?post=6611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}