{"id":9134,"date":"2024-11-05T13:55:35","date_gmt":"2024-11-05T16:55:35","guid":{"rendered":"http:\/\/sanignacioconcepcion.cl\/sitio\/?p=9134"},"modified":"2024-11-06T13:58:46","modified_gmt":"2024-11-06T16:58:46","slug":"suspension-taller-futbol-varones-y-basquetbol","status":"publish","type":"post","link":"https:\/\/sanignacioconcepcion.cl\/sitio\/suspension-taller-futbol-varones-y-basquetbol\/","title":{"rendered":"Suspensi\u00f3n taller f\u00fatbol varones y b\u00e1squetbol"},"content":{"rendered":"<p>Estimadas familias:<\/p>\n<p>Informo a ustedes que, se suspenden los siguientes talleres en los d\u00edas indicados:<\/p>\n<ul>\n<li><strong>Taller de b\u00e1squetbol:<\/strong> Suspendido damas y varones, <strong>viernes 8 de noviembre<\/strong>, desde las 15:00 horas.<\/li>\n<li><strong>Taller futbol varones:<\/strong> Suspendido todos los entrenamientos del <strong>jueves 7 y viernes 8 de noviembre<\/strong>, por participaci\u00f3n en campeonatos.<\/li>\n<\/ul>\n<p>Atentamente,<\/p>\n<p>Coordinaci\u00f3n ACLE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias: Informo a ustedes que, se suspenden los siguientes talleres en los d\u00edas indicados: Taller de b\u00e1squetbol: Suspendido damas y varones, viernes 8 de noviembre, desde las 15:00 horas. Taller futbol varones: Suspendido todos los entrenamientos del jueves 7 y viernes 8 de noviembre, por participaci\u00f3n en campeonatos. Atentamente, Coordinaci\u00f3n ACLE<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/posts\/9134"}],"collection":[{"href":"https:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/comments?post=9134"}],"version-history":[{"count":1,"href":"https:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/posts\/9134\/revisions"}],"predecessor-version":[{"id":9135,"href":"https:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/posts\/9134\/revisions\/9135"}],"wp:attachment":[{"href":"https:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/media?parent=9134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/categories?post=9134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sanignacioconcepcion.cl\/sitio\/wp-json\/wp\/v2\/tags?post=9134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}